{"id":5255,"date":"2020-06-17T08:30:13","date_gmt":"2020-06-17T06:30:13","guid":{"rendered":"https:\/\/www.coollibri.com\/blog\/?p=5255"},"modified":"2020-12-28T07:12:08","modified_gmt":"2020-12-28T06:12:08","slug":"livres-litterature-fantastique-jeunesse","status":"publish","type":"post","link":"https:\/\/www.coollibri.com\/blog\/livres-litterature-fantastique-jeunesse\/","title":{"rendered":"12 livres de litt\u00e9rature fantastique pour la jeunesse \u00e0 ne pas manquer"},"content":{"rendered":"<p style=\"text-align: justify\">La litt\u00e9rature fantastique pour la jeunesse foisonne. Elle s&rsquo;adresse \u00e0 un public, principalement, d&rsquo;adolescents et de jeunes adultes. Mais, un public plus \u00e2g\u00e9 ne la d\u00e9daigne pas non plus. Tant elle est cr\u00e9ative. Par cons\u00e9quent, il est difficile de faire une s\u00e9lection. Mais, quoi qu&rsquo;il en soit, certains ouvrages paraissent incontournables.<\/p>\n<p style=\"text-align: justify\">Pour cette raison, ils ont :<\/p>\n<ul>\n<li style=\"text-align: justify\">\u00e9t\u00e9 rep\u00e9r\u00e9s par des sp\u00e9cialistes.<\/li>\n<li style=\"text-align: justify\">re\u00e7u des prix.<\/li>\n<li style=\"text-align: justify\">fait l&rsquo;unanimit\u00e9 aupr\u00e8s des lecteurs ou encore.<\/li>\n<li style=\"text-align: justify\">fait l&rsquo;objet de films, de s\u00e9ries, ou de jeux vid\u00e9o.<\/li>\n<\/ul>\n<p style=\"text-align: justify\">Les 12 titres de la liste qui suit appartiennent \u00e0 la cat\u00e9gorie des<strong> ouvrages qu&rsquo;il faut avoir lu<\/strong>. Les \u00ab\u00a0must have\u00a0\u00bb, comme on dit.<\/p>\n<p style=\"text-align: justify\">Et, comme il se doit, ils se r\u00e9partissent en plusieurs sous genres selon, notamment, la th\u00e9matique qu&rsquo;ils d\u00e9veloppent.<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify\">Les livres de dragons<\/h2>\n<p style=\"text-align: justify\">Dans ce sous genre, les dragons ont la cote. C&rsquo;est que le dragon v\u00e9hicule avec lui une forte charge symbolique. Il est pratiquement de tous les mythes, aussi bien en Occident qu&rsquo;en Asie.<\/p>\n<p style=\"text-align: justify\">Et de tous temps. Pour faire simple, le dragon repr\u00e9sente les forces du chaos et l&rsquo;\u00e9nergie primordiale.<\/p>\n<p style=\"text-align: justify\">Ma\u00eetris\u00e9es avec sagesse, elles sont b\u00e9n\u00e9fiques, livr\u00e9es \u00e0 elles-m\u00eames ou mal comprises, elles n&rsquo;engendrent que ruines et d\u00e9sespoir. C&rsquo;est un peu la trame de ce que racontent tous les romans qui mettent en sc\u00e8ne des dragons. Comme, par exemple :<\/p>\n<h3 style=\"text-align: justify\">L&rsquo;h\u00e9ritage, de Christopher Paolini<\/h3>\n<p style=\"text-align: justify\">Publi\u00e9 par Bayard jeunesse, en 2004, l&rsquo;ouvrage comprend 4 tomes. Le <a href=\"https:\/\/amzn.to\/391ojso\" target=\"_blank\" rel=\"noopener noreferrer\">premier<\/a>, de 653 pages, est intitul\u00e9 Eragon. Le dernier, vient de para\u00eetre.<\/p>\n<p><a href=\"https:\/\/amzn.to\/391ojso\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-6501 size-medium\" src=\"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/81sb81t5ITL1-242x300.jpg\" alt=\"Litt\u00e9rature jeunesse L\u2019h\u00e9ritage, de Christopher Paolini\" width=\"242\" height=\"300\" srcset=\"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/81sb81t5ITL1-242x300.jpg 242w, https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/81sb81t5ITL1-824x1024.jpg 824w, https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/81sb81t5ITL1-768x954.jpg 768w, https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/81sb81t5ITL1-1236x1536.jpg 1236w, https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/81sb81t5ITL1.jpg 1288w\" sizes=\"(max-width: 242px) 100vw, 242px\" \/><\/a><\/p>\n<p style=\"text-align: justify\">Eragon est un jeune de 16 ans, bien ordinaire, qui d\u00e9couvre, un jour, au cours d&rsquo;une promenade en for\u00eat, une pierre bleue qui se r\u00e9v\u00e8le \u00eatre un \u0153uf de dragon. L\u2019\u0153uf \u00e9clot, Eragon \u00e9l\u00e8ve le dragon et devient dragonnier. A partir de l\u00e0, sa vie change et il doit r\u00e9soudre une multitude de probl\u00e8mes pour lib\u00e9rer et sauver le royaume de l&rsquo;Alaga\u00ebsia.<\/p>\n<p style=\"text-align: justify\">Les aventures d&rsquo;Eragon ont tellement s\u00e9duit le public qu&rsquo;elles ont donn\u00e9 lieu \u00e0 un <strong>film<\/strong>. R\u00e9alis\u00e9 par Stefen Fangmeier, il est sorti en 2006. Mais, comme c&rsquo;est souvent le cas, le film a un peu d\u00e9\u00e7u les lecteurs et les fans d&rsquo;Eragon.\u00a0<\/p>\n<p style=\"text-align: justify\">Cela dit, il n&rsquo;y pas de fum\u00e9e sans feu, et la r\u00e9alisation d&rsquo;un film est un bon marqueur de qualit\u00e9 pour le livre dont il est issu.<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: justify\">Lueur de feu, de Sophie Jordan<\/h3>\n<p style=\"text-align: justify\">Le <a href=\"https:\/\/amzn.to\/3pODc7k\" target=\"_blank\" rel=\"noopener noreferrer\">livre<\/a> a \u00e9t\u00e9 publi\u00e9 par Gallimard jeunesse en 2011. Il comprend 3 tomes. Le premier fait 336 pages.<\/p>\n<p style=\"text-align: justify\">L&rsquo;univers de \u00ab\u00a0lueur de feu\u00a0\u00bb est contemporain et Jacinda, l&rsquo;h\u00e9ro\u00efne, est une lyc\u00e9enne. Seulement voil\u00e0, elle est aussi une draki. C&rsquo;est-\u00e0-dire qu&rsquo;elle descend de dragons qui peuvent prendre forme humaine.<\/p>\n<p style=\"text-align: justify\">\u00c9videmment, elle a du mal \u00e0 contr\u00f4ler tout \u00e7a. Et cela, d&rsquo;autant plus qu&rsquo;elle a plus de pouvoirs que les autres membres de sa famille. Certes, elle peut voler, mais, surtout, elle peut cracher du feu.<\/p>\n<p><a href=\"https:\/\/amzn.to\/3pODc7k\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-6502\" src=\"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/71YtsydiceL1-181x300.jpg\" alt=\"\" width=\"181\" height=\"300\" srcset=\"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/71YtsydiceL1-181x300.jpg 181w, https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/71YtsydiceL1-617x1024.jpg 617w, https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/71YtsydiceL1.jpg 712w\" sizes=\"(max-width: 181px) 100vw, 181px\" \/><\/a><\/p>\n<p style=\"text-align: justify\">D&rsquo;o\u00f9 la question pos\u00e9e : comment vivre normalement dans un monde qui n&rsquo;accepte pas la diff\u00e9rence, surtout, quand cette diff\u00e9rence est hors norme et conf\u00e8re des super pouvoirs ?<\/p>\n<blockquote>\n<p>En regardant ce lac paisible, je suis persuad\u00e9e que le risque en vaut la peine. Azure arrive, essouffl\u00e9e. Elle ne prend pas la peine de mettre la b\u00e9quille. Son v\u00e9lo tombe bruyamment par terre, \u00e0 c\u00f4t\u00e9 du mien&#8230; &#8211; On ne devrait pas faire \u00e7a, Jacinda&#8230; dit-elle.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify\">Ainsi commence la saga de Jacinda, Lueur de feu.<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: justify\">Harold et les dragons, de Cressida Cowell<\/h3>\n<p style=\"text-align: justify\">La saga fantastique qui comprend 11 volumes dont 9 ont seulement ont \u00e9t\u00e9 traduits en fran\u00e7ais s&rsquo;adresse plus particuli\u00e8rement aux <strong>jeunes de 9 \u00e0 12 ans<\/strong>. Elle commence par le titre \u00ab\u00a0<a href=\"https:\/\/amzn.to\/3ffAD9L\" target=\"_blank\" rel=\"noopener noreferrer\">Comment dresser votre dragon<\/a>\u00ab\u00a0.<\/p>\n<p style=\"text-align: justify\">Tout un programme. Mais, un guide n\u00e9cessaire quand on est un jeune viking \u00e0 qui on demande de faire ses preuves et qui malheureusement n&rsquo;a qu&rsquo;un petit dragon pour l&rsquo;aider.<\/p>\n<p><a href=\"https:\/\/amzn.to\/3ffAD9L\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-6503\" src=\"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/91H99aJfLhL1-187x300.jpg\" alt=\"litterature jeunesse Harold et les dragons, de Cressida Cowell\" width=\"187\" height=\"300\" srcset=\"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/91H99aJfLhL1-187x300.jpg 187w, https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/91H99aJfLhL1-638x1024.jpg 638w, https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/91H99aJfLhL1-768x1233.jpg 768w, https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/91H99aJfLhL1-957x1536.jpg 957w, https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/91H99aJfLhL1-1275x2048.jpg 1275w, https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/91H99aJfLhL1.jpg 1400w\" sizes=\"(max-width: 187px) 100vw, 187px\" \/><\/a><\/p>\n<p style=\"text-align: justify\">Les premiers volumes ont \u00e9t\u00e9 publi\u00e9s par <strong>Casterman<\/strong>, \u00e0 partir de 2010, puis par <strong>Hachette romans<\/strong>. A noter que la saga a donn\u00e9 lieu \u00e0 la r\u00e9alisation d&rsquo;un <strong>film d&rsquo;animation en 3 D<\/strong> qui a rencontr\u00e9 un \u00e9norme succ\u00e8s et qui a \u00e9t\u00e9 couvert de r\u00e9compenses. De ce film a \u00e9t\u00e9, par ailleurs, d\u00e9riv\u00e9e une s\u00e9rie t\u00e9l\u00e9vis\u00e9e diffus\u00e9e d&rsquo;abord par Cartoon Network, puis par Netflix.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">Et elle est source d&rsquo;inspiration pour de nombreux youtubeurs, comme univers dragons :<\/p>\n<p><iframe loading=\"lazy\" title=\"Sp\u00e9ciale 100 Abonn\u00e9s ! L&#039; amiti\u00e9 de Harold et Krokmou\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/4YjTNKlupLY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p style=\"text-align: justify\">\u00a0<\/p>\n<h2 style=\"text-align: justify\">Romans fantastiques de sorci\u00e8res et de magiciens<\/h2>\n<p style=\"text-align: justify\">Ces romans revisitent d&rsquo;autres mythes, plus modernes, notamment le <a href=\"http:\/\/philofrancais.fr\/mythe-de-faust\" target=\"_blank\" rel=\"noopener noreferrer\">mythe de Faust<\/a>, champion des \u00e9preuves du bac philo, et le <a href=\"https:\/\/www.lesauterhin.eu\/lapprenti-sorcier-une-ballade-de-goethe\/\" target=\"_blank\" rel=\"noopener noreferrer\">mythe de l&rsquo;apprenti sorcier<\/a>. En g\u00e9n\u00e9ral, \u00e7a commence avec la surprise et le bonheur de pouvoir acc\u00e9der \u00e0 un savoir supr\u00eame gr\u00e2ce auquel tout devient possible. Puis, au fil de leur aventures, les h\u00e9ros finissent par se rendre compte que ce savoir peut \u00eatre encombrant, nuisible m\u00eame, et les conduire dans des situations limites.<\/p>\n<p style=\"text-align: justify\">D&rsquo;o\u00f9 ils ne sortent que rarement indemnes. En tout cas, les \u00e9preuves qu&rsquo;ils subissent, \u00e0 cause de leurs connaissances, les changent.<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: justify\">Harry Potter, de J.K Rowling<\/h3>\n<p style=\"text-align: justify\">Le plus c\u00e9l\u00e8bre de ces romans est, bien s\u00fbr, la saga d&rsquo;Harry Potter et ses <a href=\"https:\/\/amzn.to\/3fihLqL\" target=\"_blank\" rel=\"noopener noreferrer\">7 volumes<\/a>. Le premier s&rsquo;intitule \u00ab\u00a0A l&rsquo;\u00e9cole des sorciers\u00a0\u00bb. Tir\u00e9 \u00e0 500 exemplaires par Bloomsbury, en 1997, sa version fran\u00e7aise a \u00e9t\u00e9 publi\u00e9 en France d\u00e8s 1998, par Gallimard Jeunesse.<\/p>\n<p style=\"text-align: justify\">Un des exemplaires de la premi\u00e8re \u00e9dition anglaise vient d&rsquo;\u00eatre vendu aux ench\u00e8res pour 33 000 livres. Le fait qu&rsquo;en un peu plus de 20 ans, Harry Potter a conquis pr\u00e8s de 500 millions de lecteurs, dont pr\u00e8s de 30 en France.<\/p>\n<p><a href=\"https:\/\/amzn.to\/3fihLqL\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-6505\" src=\"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/810oxkOwz4L1-300x229.jpg\" alt=\"litt\u00e9rature jeunesse Harry Potter \" width=\"300\" height=\"229\" srcset=\"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/810oxkOwz4L1-300x229.jpg 300w, https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/810oxkOwz4L1-1024x783.jpg 1024w, https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/810oxkOwz4L1-768x587.jpg 768w, https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/810oxkOwz4L1-1536x1174.jpg 1536w, https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/810oxkOwz4L1.jpg 2000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify\">Quant \u00e0 l&rsquo;histoire, on ne la pr\u00e9sente plus.\u00a0 Elle a fait l&rsquo;objet d&rsquo;une adaptation au cin\u00e9ma. En 8 films, celle-ci a g\u00e9n\u00e9r\u00e9 pr\u00e8s de 8 milliards de dollars de recettes et a rassembl\u00e9 devant les \u00e9crans, en France, un peu plus de 58 millions de spectateurs. Des chiffres qui donnent le tournis, sans doute le premier r\u00e9sultat de la magie du petit sorcier invent\u00e9 par J.K Rowling.<\/p>\n<p style=\"text-align: justify\">Un dernier mot pour dire que la saga fait partie de ce qu&rsquo;on appelle la \u00ab\u00a0low fantasy\u00a0\u00bb par opposition \u00e0 la \u00ab\u00a0high fantasy\u00a0\u00bb. Dans l&rsquo;un et l&rsquo;autre, la magie joue un r\u00f4le central, mais alors que dans la \u00ab\u00a0<strong>low fantasy<\/strong>\u00ab\u00a0, l&rsquo;univers est contemporain, dans la \u00ab\u00a0<strong>high fantasy<\/strong>\u00ab\u00a0, il est lui aussi magique. Traduit en fran\u00e7ais, la \u00ab\u00a0low fantasy\u00a0\u00bb devient le sous genre \u00ab\u00a0<strong>fantastique<\/strong>\u00a0\u00bb et la \u00ab\u00a0high fantasy\u00a0\u00bb, le sous-genre \u00ab\u00a0<strong>fantasy<\/strong>\u00ab\u00a0.<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: justify\">Percy Jackson, de Rick Riordan<\/h3>\n<p style=\"text-align: justify\">La saga de Percy Jackson comprend 7 volumes. L&rsquo;auteur est am\u00e9ricain et a \u00e9t\u00e9 publi\u00e9, \u00e0 partir de 2005, pratiquement en simultan\u00e9, par la maison d&rsquo;\u00e9dition new yorkaise Miramax Books et la maison d&rsquo;\u00e9dition fran\u00e7aise, Albin Michel. Le premier volume s&rsquo;intitule \u00ab\u00a0<a href=\"https:\/\/amzn.to\/3nEWDhc\" target=\"_blank\" rel=\"noopener noreferrer\">Le voleur de foudre<\/a>\u00ab\u00a0.<\/p>\n<p style=\"text-align: justify\">L&rsquo;histoire se d\u00e9roule \u00e0 l&rsquo;\u00e9poque actuelle. Oui, mais voil\u00e0, Percy, qui a douze ans au moment o\u00f9 d\u00e9bute l&rsquo;histoire, d\u00e9couvre qu&rsquo;il est, en fait, le fils du dieu grec, <strong>Pos\u00e9idon<\/strong>. Occasion pour l&rsquo;auteur de remettre au go\u00fbt du jour tout le <strong>panth\u00e9on des dieux grecs<\/strong> et la symbolique qu&rsquo;ils repr\u00e9sentent.<\/p>\n<p style=\"text-align: justify\">Le tome 7, \u00ab\u00a0Percy Jackson et les h\u00e9ros grecs\u00a0\u00bb ne relate pas, \u00e0 proprement parler, une aventure du h\u00e9ros. Mais, elle permet de faire le point sur les diff\u00e9rents dieux grecs, de mani\u00e8re romanc\u00e9e et contemporaine.<\/p>\n<p style=\"text-align: justify\">Percy Jackson a fait l&rsquo;objet de deux adaptations cin\u00e9matographiques. \u00ab\u00a0Le voleur de foudre\u00a0\u00bb en 2010 et \u00ab\u00a0La mer des monstres\u00a0\u00bb en 2013.<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: justify\">Les chevaliers d&rsquo;Emeraude, de Anne Robillard<\/h3>\n<p style=\"text-align: justify\">Publi\u00e9e pour la premi\u00e8re fois au Canada par l&rsquo;\u00e9diteur Mortagne, en 2003, la saga qui ne comprend pas moins de <a href=\"https:\/\/amzn.to\/35Luw9S\" target=\"_blank\" rel=\"noopener noreferrer\">12 volumes<\/a>, est publi\u00e9e, en France, par la maison d&rsquo;\u00e9dition<strong> Michel Lafon<\/strong>, depuis 2007. L&rsquo;histoire commence avec \u00ab\u00a0Le feu dans le ciel\u00a0\u00bb et se d\u00e9roule, principalement, sur le continent imaginaire d&rsquo;Enkidiev. Apr\u00e8s des si\u00e8cles de paix, le continent est menac\u00e9 par les forces du mal, mais les chevaliers d&rsquo;\u00e9meraude, 6 hommes et une femme, veillent au grain.<\/p>\n<p style=\"text-align: justify\">Ils vont emp\u00eacher l&#8217;empereur Noir, Amecareth, de mener ses sombres desseins \u00e0 leur terme.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_5303\" aria-describedby=\"caption-attachment-5303\" style=\"width: 347px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/amzn.to\/35Luw9S\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5303\" src=\"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/Les-chevaliers-dEmeraude-de-Anne-Robillard-224x300.jpg\" alt=\"Les chevaliers d'Emeraude, de Anne Robillard\" width=\"347\" height=\"465\" srcset=\"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/Les-chevaliers-dEmeraude-de-Anne-Robillard-224x300.jpg 224w, https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/Les-chevaliers-dEmeraude-de-Anne-Robillard-766x1024.jpg 766w, https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/Les-chevaliers-dEmeraude-de-Anne-Robillard-768x1027.jpg 768w, https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/Les-chevaliers-dEmeraude-de-Anne-Robillard-1149x1536.jpg 1149w, https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/Les-chevaliers-dEmeraude-de-Anne-Robillard.jpg 1422w\" sizes=\"(max-width: 347px) 100vw, 347px\" \/><\/a><figcaption id=\"caption-attachment-5303\" class=\"wp-caption-text\">Les chevaliers d&rsquo;Emeraude, de Anne Robillard<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">On est en plein dans ce qu&rsquo;on appelle l&rsquo;<strong>heroic fantasy<\/strong>. La saga a \u00e9t\u00e9 lue par pr\u00e8s d&rsquo;un million de lecteurs au Canada et par plusieurs dizaines de milliers en France, d\u00e8s sa parution. Apparemment trop complexe, la saga n&rsquo;a pas encore fait l&rsquo;objet d&rsquo;une adaptation au cin\u00e9ma. Cela, malgr\u00e9 les nombreuses sollicitations faites aupr\u00e8s de l&rsquo;auteure. A d\u00e9faut, on peut toujours se reporter \u00e0 la BD qu&rsquo;Anne Robillard a r\u00e9alis\u00e9 avec Tiburce Oger et disponible chez Casterman.<\/p>\n<p style=\"text-align: justify\">Accessible d\u00e8s 12 ans, la saga d&rsquo;Anne Robillard, \u00e9crite dans un langage simple, est une excellente pr\u00e9paration \u00e0 la lecture de cette \u0153uvre majeure de la litt\u00e9rature fantastique mondiale qu&rsquo;est \u00a0\u00bb <strong>Le seigneur des anneaux<\/strong>\u00a0\u00bb de<strong> J.R.R Tolkien<\/strong>.<\/p>\n<p style=\"text-align: justify\">\u00a0<\/p>\n<h2 style=\"text-align: justify\">Dark fantasy et atmosph\u00e8re fantastique de fin du monde<\/h2>\n<p style=\"text-align: justify\">La litt\u00e9rature fantastique jeunesse refl\u00e8te, comme celle destin\u00e9e \u00e0 un public plus \u00e2g\u00e9, les pr\u00e9occupations de l&rsquo;\u00e9poque et ses angoisses. Un bel exemple est fourni par \u00ab\u00a0<strong>Games of thrones<\/strong>\u00a0\u00bb de <strong>George R.R Martin.<\/strong> Inspir\u00e9 de faits historiques r\u00e9els, transpos\u00e9s dans un univers imaginaire, 9 clans s&rsquo;y affrontent dans l&rsquo;espoir d&rsquo;occuper le tr\u00f4ne de fer et d&rsquo;obtenir le pouvoir supr\u00eame.<\/p>\n<p style=\"text-align: justify\">Le tout sur fond d&rsquo;apocalypse \u00e0 venir, dont l&rsquo;antienne r\u00e9currente \u00ab\u00a0Winter is coming \u00a0\u00bb est le symbole. A des degr\u00e9s divers, les 3 ouvrages suivants ont une approche romanesque similaire.<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: justify\">La saga du sorceleur, d&rsquo;Andrzej Sapkowski<\/h3>\n<p style=\"text-align: justify\">Publi\u00e9e en France par <strong>Bragelonne,<\/strong> \u00e0 partir de 2008, la saga comprend <a href=\"https:\/\/amzn.to\/3pTCR3F\" target=\"_blank\" rel=\"noopener noreferrer\">5 volumes<\/a>. Le premier s&rsquo;intitule \u00ab\u00a0Le dernier voeu\u00a0\u00bb.<\/p>\n<p style=\"text-align: justify\">Elle relate des \u00e9v\u00e8nements \u00e0 un moment o\u00f9 ce qui avait fait l&rsquo;\u00e9quilibre d&rsquo;un monde est en train de dispara\u00eetre. Sous l&rsquo;impulsion de forces obscures, un nouveau monde d\u00e9barrass\u00e9 de ce qui faisait sa diversit\u00e9 est en train d&rsquo;\u00e9merger. Les circonstances font d&rsquo;un sorceleur, G\u00e9ralt de Riv, un \u00eatre g\u00e9n\u00e9tiquement modifi\u00e9, une sorte de \u00ab\u00a0passerelle\u00a0\u00bb entre les deux mondes.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_5309\" aria-describedby=\"caption-attachment-5309\" style=\"width: 340px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/amzn.to\/3pTCR3F\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5309\" src=\"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/La-saga-du-sorceleur-d\u2019Andrzej-Sapkowski-194x300.jpg\" alt=\"La saga du sorceleur, d\u2019Andrzej Sapkowski\" width=\"340\" height=\"525\" srcset=\"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/La-saga-du-sorceleur-d\u2019Andrzej-Sapkowski-194x300.jpg 194w, https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/La-saga-du-sorceleur-d\u2019Andrzej-Sapkowski-662x1024.jpg 662w, https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/La-saga-du-sorceleur-d\u2019Andrzej-Sapkowski-768x1188.jpg 768w, https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/La-saga-du-sorceleur-d\u2019Andrzej-Sapkowski-993x1536.jpg 993w, https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/La-saga-du-sorceleur-d\u2019Andrzej-Sapkowski-1324x2048.jpg 1324w, https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/La-saga-du-sorceleur-d\u2019Andrzej-Sapkowski.jpg 1356w\" sizes=\"(max-width: 340px) 100vw, 340px\" \/><\/a><figcaption id=\"caption-attachment-5309\" class=\"wp-caption-text\">La saga du sorceleur, d\u2019Andrzej Sapkowski<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">La coloration de l&rsquo;univers fantastique dans lequel la narration se d\u00e9veloppe doit beaucoup aux <strong>mythes slaves, <\/strong>dont<strong> le <a href=\"https:\/\/mythologica.fr\/nordique\/ragnarok.htm\" target=\"_blank\" rel=\"noopener noreferrer\">Ragnar\u00f6k.<\/a><\/strong> De m\u00eame qu&rsquo;\u00e0 l&rsquo;histoire polonaise, pays d&rsquo;origine de l&rsquo;auteur. Et, comme le dit le r\u00e9sum\u00e9 de 4 \u00e8me de couverture du tome 2 :<\/p>\n<blockquote>\n<p style=\"text-align: justify\">Fid\u00e8le aux r\u00e8gles de la corporation maudite des sorceleurs, G\u00e9ralt assume sa mission sans faillir dans un monde hostile et corrompu qui ne laisse aucune place \u00e0 l&rsquo;espoir. Mais, la rencontre avec la petite Ciri, l&rsquo;Enfant \u00e9lue, dont il va assurer la protection, va donner un nouveau sens \u00e0 l&rsquo;existence de ce h\u00e9ros solitaire.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify\">Laur\u00e9ate, en 2009, du David Gemmell Legend award du meilleur roman de fantasy, la saga ne cesse de conqu\u00e9rir de nouveaux lecteurs et est devenue en quelques ann\u00e9es un vrai ph\u00e9nom\u00e8ne d&rsquo;\u00e9dition. Le fait est, qu&rsquo;outre ses qualit\u00e9s litt\u00e9raires, la saga a b\u00e9n\u00e9fici\u00e9 du succ\u00e8s du jeu vid\u00e9o, \u00ab\u00a0the witcher\u00a0\u00bb qui s&rsquo;en est inspir\u00e9. Du jeu vid\u00e9o \u00e0 l&rsquo;adaptation cin\u00e9matographique, il n&rsquo;y a qu&rsquo;un pas qui a \u00e9t\u00e9 franchi avec la production par Netflix d&rsquo;une saison de 8 \u00e9pisodes.<\/p>\n<p style=\"text-align: justify\">Devant le succ\u00e8s obtenu par la premi\u00e8re, une deuxi\u00e8me est en pr\u00e9paration et devrait bient\u00f4t sortir.<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: justify\">Stranger things : Suspicious minds, de Gwenda Bond<\/h3>\n<p style=\"text-align: justify\">Le roman de 512 pages a la particularit\u00e9 de faire suite \u00e0 la s\u00e9rie \u00e0 succ\u00e8s, du m\u00eame nom, diffus\u00e9e par Netflix et d&rsquo;en donner les clefs. C&rsquo;est donc une <a href=\"https:\/\/www.larousse.fr\/dictionnaires\/francais\/pr%C3%A9quelle\/10910855\" target=\"_blank\" rel=\"noopener noreferrer\">pr\u00e9quelle<\/a>. Il est publi\u00e9 par les \u00e9ditions Lumen.<\/p>\n<p style=\"text-align: justify\">Un deuxi\u00e8me tome, de 607 pages, est \u00e9galement paru, aux m\u00eames \u00e9ditions, sous le titre \u00ab\u00a0Stranger things : Darkness on the edge of town\u00a0\u00bb et un troisi\u00e8me est en pr\u00e9paration. A noter, par ailleurs, qu&rsquo;il existe une version sous forme de BD.<\/p>\n<p style=\"text-align: justify\">Ces ouvrages d\u00e9crivent une r\u00e9alit\u00e9 fantastique, peupl\u00e9e d&rsquo;\u00e9tranges cr\u00e9atures, issue d&rsquo;exp\u00e9riences de laboratoire men\u00e9es dans le cadre du programme MK-Ultra de la CIA. Le contexte est donc contemporain et l&rsquo;histoire se d\u00e9roule sur plusieurs d\u00e9cennies \u00e0 partir des ann\u00e9es 60. C&rsquo;est, bien s\u00fbr, une \u0153uvre de fiction, mais le<a href=\"https:\/\/www.cia.gov\/library\/readingroom\/search\/site\/mk%20ultra\" target=\"_blank\" rel=\"noopener noreferrer\"> projet MK-Ultra<\/a>, qui lui sert de toile de fond, a bien exist\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: justify\">L&rsquo;enfant de la poussi\u00e8re, de Patrick Dewdney<\/h3>\n<p style=\"text-align: justify\">Le roman correspond au premier tome, de 600 pages, du <strong>cycle de Syffe. <\/strong>Lequel en comprend 2. Il a \u00e9t\u00e9 publi\u00e9 par les \u00e9ditions Au diable Vauvert en 2018. L&rsquo;auteur, Patrick K. Dewdney, est d&rsquo;origine britannique. Mais, il vit en France et \u00e9crit en fran\u00e7ais. Il a \u00e9t\u00e9 laur\u00e9at du <strong>grand prix de l&rsquo;imaginaire 2019<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_5305\" aria-describedby=\"caption-attachment-5305\" style=\"width: 479px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-5305\" src=\"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/Lenfant-de-la-poussi\u00e8re-de-Patrick-Dewdney-300x300.jpg\" alt=\"L'enfant de la poussi\u00e8re, de Patrick Dewdney\" width=\"479\" height=\"479\" srcset=\"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/Lenfant-de-la-poussi\u00e8re-de-Patrick-Dewdney-300x300.jpg 300w, https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/Lenfant-de-la-poussi\u00e8re-de-Patrick-Dewdney-150x150.jpg 150w, https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/Lenfant-de-la-poussi\u00e8re-de-Patrick-Dewdney-768x768.jpg 768w, https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/Lenfant-de-la-poussi\u00e8re-de-Patrick-Dewdney-400x400.jpg 400w, https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/Lenfant-de-la-poussi\u00e8re-de-Patrick-Dewdney.jpg 960w\" sizes=\"(max-width: 479px) 100vw, 479px\" \/><figcaption id=\"caption-attachment-5305\" class=\"wp-caption-text\">L&rsquo;enfant de la poussi\u00e8re, de Patrick Dewdney<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">Il raconte les aventures de Syffe, jeune orphelin des rues, dans un monde en plein chaos et soumis au bon vouloir des seigneurs de guerre. De fait, les primeaut\u00e9s de Corne-Brune ne manqueront pas d&rsquo;\u00e9voquer certaines contr\u00e9es actuelles. Pour un lecteur enthousiaste :<\/p>\n<blockquote>\n<p style=\"text-align: justify\">Syffe est un petit gar\u00e7on d\u00e9brouillard qui vit au jour le jour, entour\u00e9 d&rsquo;une petite bande d&rsquo;enfants au parcours similaire au sien. Et puis, une succession d&rsquo;\u00e9v\u00e8nements va totalement transformer le quotidien du petit vagabond qui va d\u00e8s lors passer par une multitude de statuts tr\u00e8s vari\u00e9s auxquels il va devoir s&rsquo;habituer.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify\">\u00a0<\/p>\n<h2 style=\"text-align: justify\">Litt\u00e9rature jeunesse fantastique prim\u00e9e en 2019<\/h2>\n<p style=\"text-align: justify\">La litt\u00e9rature jeunesse fantastique a ses prix : le <strong>prix Vendredi,<\/strong> r\u00e9cemment lanc\u00e9 par le syndicat national des \u00e9diteurs (SNE), le<strong> Grand Prix de l&rsquo;Imaginaire, dit GPI<\/strong>, le plus ancien, et le <strong>prix Sorci\u00e8res<\/strong>. Ce dernier est attribu\u00e9 par l&rsquo;association des librairies sp\u00e9cialis\u00e9es pour la jeunesse (ASLJ) et l&rsquo;association des biblioth\u00e9caires de France (ABF).<\/p>\n<h3 style=\"text-align: justify\">L&rsquo;estrange malaventure de Mirella, de Flore Vesco<\/h3>\n<p style=\"text-align: justify\">Publi\u00e9 par la maison d&rsquo;\u00e9ditions, \u00ab\u00a0L&rsquo;\u00e9cole des loisirs\u00a0\u00bb, le roman a re\u00e7u le<strong> Prix Vendredi 2019<\/strong>. Il raconte l&rsquo;histoire d&rsquo;une adolescente, Mirella, qui vit dans la ville d&rsquo;Hamelin, au 13 \u00e8me si\u00e8cle. \u00c9videmment, on pense imm\u00e9diatement au joueur de fl\u00fbte du conte de Grimm.<\/p>\n<p style=\"text-align: justify\">Mais, la \u00ab\u00a0v\u00e9ritable\u00a0\u00bb histoire racont\u00e9e, dans une langue savoureuse, par Flore Vesco est bien diff\u00e9rente. Ci-apr\u00e8s un court extrait illustrant le style original de l&rsquo;auteure :<\/p>\n<blockquote>\n<p style=\"text-align: justify\">Au commencement du mois de juillet, le soleil d\u00e9cida qu&rsquo;Hamelin ferait une r\u00f4tissoire id\u00e9ale. Il semblait qu&rsquo;une douche de feu vous tombait sur le cr\u00e2ne d\u00e8s que vous mettiez le nez dehors. Aux heures les plus chaudes, les braves habitants restaient \u00e0 l&rsquo;ombre, endurant vaillamment cette insuff\u00e9rable chaleur.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify\">\u00a0<\/p>\n<h3 style=\"text-align: justify\">Roslend, de Nathalie Somers<\/h3>\n<p style=\"text-align: justify\">\u00c9galement laur\u00e9at du <strong>Grand Prix de l&rsquo;Imaginaire 2019<\/strong>, la trilogie de Nathalie Somers a \u00e9t\u00e9 publi\u00e9, en 2017, par la maison d&rsquo;\u00e9dition Didier Jeunesse. Il m\u00eale personnages historiques, comme Winston Churchill ou le G\u00e9n\u00e9ral de Gaulle, dans une histoire qui se passe en 1940.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_5307\" aria-describedby=\"caption-attachment-5307\" style=\"width: 349px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/amzn.to\/332aqGV\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5307\" src=\"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/Roslend-de-Nathalie-Somers-205x300.jpg\" alt=\"Roslend, de Nathalie Somers\" width=\"349\" height=\"511\" srcset=\"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/Roslend-de-Nathalie-Somers-205x300.jpg 205w, https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/Roslend-de-Nathalie-Somers-700x1024.jpg 700w, https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/Roslend-de-Nathalie-Somers-768x1123.jpg 768w, https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/Roslend-de-Nathalie-Somers-1051x1536.jpg 1051w, https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/Roslend-de-Nathalie-Somers.jpg 1400w\" sizes=\"(max-width: 349px) 100vw, 349px\" \/><\/a><figcaption id=\"caption-attachment-5307\" class=\"wp-caption-text\">Roslend, de Nathalie Somers<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">Cela pour le c\u00f4t\u00e9 r\u00e9aliste. Quant au c\u00f4t\u00e9 fantastique.\u00a0 Il vient de ce que les deux h\u00e9ros, Lucan et Catriona, 28 ans \u00e0 tous les deux, h\u00e9ritent d&rsquo;une cl\u00e9 aux pouvoirs surnaturels.<\/p>\n<p style=\"text-align: justify\">En effet, elle peut les faire passer dans un univers parall\u00e8le. On n&rsquo;est pas loin du \u00ab\u00a0Monde de Narnia\u00a0\u00bb. Or, cet autre univers est lui aussi en guerre. Et, ce qui ce qui se passe dans l&rsquo;un a des r\u00e9percussions dans ce qui se passe dans l&rsquo;autre. De sorte que, selon une lectrice :<\/p>\n<blockquote>\n<p>1er chapitre : immersion imm\u00e9diate. 2nd chapitre : l&rsquo;auteure m&rsquo;a bluff\u00e9. En 10 pages, elle m&rsquo;a rendu addict.<\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: justify\">L\u00e9gende de Podkin le brave, de Kieran Laswood<\/h3>\n<p style=\"text-align: justify\">La trilogie s&rsquo;adresse \u00e0 un jeune public de 9 \u00e0 13 ans. Publi\u00e9e par la maison d&rsquo;\u00e9dition Gallimard jeunesse, elle met en sc\u00e8ne dans son premier tome qui s&rsquo;intitule \u00ab\u00a0Naissance d&rsquo;un chef\u00a0\u00bb, un lapin fac\u00e9tieux et insouciant. Mais, il va devoir lutter pour d\u00e9fendre sa communaut\u00e9 contre les Gorm, d&rsquo;affreux lapins, v\u00eatus de m\u00e9tal. Et ce faisant, il va se transformer pour accomplir sa destin\u00e9e.<\/p>\n<p style=\"text-align: justify\">L&rsquo;ouvrage a re\u00e7u le <strong>Prix Sorci\u00e8res 2019<\/strong> dans la cat\u00e9gorie \u00ab\u00a0Carr\u00e9ment passionnant mini\u00a0\u00bbet le prix anglais de litt\u00e9rature jeunesse <strong>Blue Peter 2017<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify\">La litt\u00e9rature fantastique jeunesse un genre litt\u00e9raire \u00e0 part enti\u00e8re<\/h2>\n<p style=\"text-align: justify\">En effet, les ouvrages de litt\u00e9rature fantastique pour la jeunesse sont on ne peut plus s\u00e9rieux. Car, ils contraignent les \u00e9crivains \u00e0 faire preuve de didactisme, de clart\u00e9 et d&rsquo;invention. Cela tient au caract\u00e8re tr\u00e8s exigeant et tr\u00e8s demandeur du jeune public.<\/p>\n<p>D&rsquo;ailleurs, nous livrons quelques <a href=\"https:\/\/www.coollibri.com\/blog\/comment-ecrire-un-roman-pour-ados\/\" target=\"_blank\" rel=\"noopener noreferrer\">cl\u00e9s pour \u00e9crire un roman pour ados<\/a>.<\/p>\n<p style=\"text-align: justify\">L&rsquo;\u00e9criture de ce genre de roman par les auteurs amateurs ou \u00e9crivains confim\u00e9s n&rsquo;est pas un ph\u00e9nom\u00e8ne nouveau. A tel point que certains de ces ouvrages sont devenus des monuments de la litt\u00e9rature mondiale. Comme, par exemple, \u00ab\u00a0Le petit Prince\u00a0\u00bb, \u00ab\u00a0Les voyages de Gulliver\u00a0\u00bb ou encore \u00ab\u00a0Les aventures de Tom Sawyer\u00a0\u00bb.<\/p>\n<p style=\"text-align: justify\">De sorte que, rien d&rsquo;\u00e9tonnant \u00e0 ce que les <a href=\"https:\/\/www.coollibri.com\/blog\/maisons-edition-specialisees-dans-la-litterature-jeunesse\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u00e9diteurs de litt\u00e9rature jeunesse<\/a> se soient multipli\u00e9s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La litt\u00e9rature fantastique pour la jeunesse foisonne. Elle s&rsquo;adresse \u00e0 un public, principalement, d&rsquo;adolescents et de jeunes adultes. Mais, un public plus \u00e2g\u00e9 ne la d\u00e9daigne pas non plus. Tant elle est cr\u00e9ative. Par cons\u00e9quent, il est difficile de faire une s\u00e9lection. Mais, quoi qu&rsquo;il en soit, certains ouvrages paraissent incontournables. Pour cette raison, ils [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":5300,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[2],"tags":[403,401,402,400],"class_list":["post-5255","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ecrire-un-livre","tag-livres-daventures-fantastiquess","tag-livres-de-dragons","tag-livres-de-magiciens","tag-livres-fantastiques-pour-la-jeunesse"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>La litt\u00e9rature fantastique pour la jeunesse est un genre plein de ressources<\/title>\r\n<meta name=\"description\" content=\"La litt\u00e9rature fantastique est un bon moyen pour la jeunesse de d\u00e9couvrir ce que la lecture peut apporter pour son d\u00e9veloppement personnel.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.coollibri.com\/blog\/livres-litterature-fantastique-jeunesse\/\" \/>\r\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"La litt\u00e9rature fantastique pour la jeunesse est un genre plein de ressources\" \/>\r\n<meta property=\"og:description\" content=\"La litt\u00e9rature fantastique est un bon moyen pour la jeunesse de d\u00e9couvrir ce que la lecture peut apporter pour son d\u00e9veloppement personnel.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.coollibri.com\/blog\/livres-litterature-fantastique-jeunesse\/\" \/>\r\n<meta property=\"og:site_name\" content=\"\u00c9crire un livre et auto\u00e9dition, le blog.\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CoolLibri\" \/>\r\n<meta property=\"article:published_time\" content=\"2020-06-17T06:30:13+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2020-12-28T06:12:08+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/12-livres-de-litt\u00e9rature-fantastique.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\r\n\t<meta property=\"og:image:height\" content=\"500\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"CoolLibri Impression de livre\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@coollibri\" \/>\r\n<meta name=\"twitter:site\" content=\"@coollibri\" \/>\r\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"CoolLibri Impression de livre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutes\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.coollibri.com\/blog\/livres-litterature-fantastique-jeunesse\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.coollibri.com\/blog\/livres-litterature-fantastique-jeunesse\/\"},\"author\":{\"name\":\"CoolLibri Impression de livre\",\"@id\":\"https:\/\/www.coollibri.com\/blog\/#\/schema\/person\/5105fe42ec9d3fe2661138a0d65013c7\"},\"headline\":\"12 livres de litt\u00e9rature fantastique pour la jeunesse \u00e0 ne pas manquer\",\"datePublished\":\"2020-06-17T06:30:13+00:00\",\"dateModified\":\"2020-12-28T06:12:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.coollibri.com\/blog\/livres-litterature-fantastique-jeunesse\/\"},\"wordCount\":3047,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/www.coollibri.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.coollibri.com\/blog\/livres-litterature-fantastique-jeunesse\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/12-livres-de-litt\u00e9rature-fantastique.jpg\",\"keywords\":[\"livres d'aventures fantastiquess\",\"livres de dragons\",\"livres de magiciens\",\"livres fantastiques pour la jeunesse\"],\"articleSection\":[\"\u00c9crire un livre\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.coollibri.com\/blog\/livres-litterature-fantastique-jeunesse\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.coollibri.com\/blog\/livres-litterature-fantastique-jeunesse\/\",\"url\":\"https:\/\/www.coollibri.com\/blog\/livres-litterature-fantastique-jeunesse\/\",\"name\":\"La litt\u00e9rature fantastique pour la jeunesse est un genre plein de ressources\",\"isPartOf\":{\"@id\":\"https:\/\/www.coollibri.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.coollibri.com\/blog\/livres-litterature-fantastique-jeunesse\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.coollibri.com\/blog\/livres-litterature-fantastique-jeunesse\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/12-livres-de-litt\u00e9rature-fantastique.jpg\",\"datePublished\":\"2020-06-17T06:30:13+00:00\",\"dateModified\":\"2020-12-28T06:12:08+00:00\",\"description\":\"La litt\u00e9rature fantastique est un bon moyen pour la jeunesse de d\u00e9couvrir ce que la lecture peut apporter pour son d\u00e9veloppement personnel.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.coollibri.com\/blog\/livres-litterature-fantastique-jeunesse\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.coollibri.com\/blog\/livres-litterature-fantastique-jeunesse\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.coollibri.com\/blog\/livres-litterature-fantastique-jeunesse\/#primaryimage\",\"url\":\"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/12-livres-de-litt\u00e9rature-fantastique.jpg\",\"contentUrl\":\"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/12-livres-de-litt\u00e9rature-fantastique.jpg\",\"width\":1500,\"height\":500,\"caption\":\"12 livres de litt\u00e9rature fantastique\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.coollibri.com\/blog\/livres-litterature-fantastique-jeunesse\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.coollibri.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"12 livres de litt\u00e9rature fantastique pour la jeunesse \u00e0 ne pas manquer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.coollibri.com\/blog\/#website\",\"url\":\"https:\/\/www.coollibri.com\/blog\/\",\"name\":\"\u00c9crire un livre et auto\u00e9dition, le blog.\",\"description\":\"Faites une bonne impression\",\"publisher\":{\"@id\":\"https:\/\/www.coollibri.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.coollibri.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.coollibri.com\/blog\/#organization\",\"name\":\"CoolLibri - Impression de livre - Auto\u00e9dition\",\"url\":\"https:\/\/www.coollibri.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.coollibri.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/2018\/03\/logo.png\",\"contentUrl\":\"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/2018\/03\/logo.png\",\"width\":231,\"height\":72,\"caption\":\"CoolLibri - Impression de livre - Auto\u00e9dition\"},\"image\":{\"@id\":\"https:\/\/www.coollibri.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/CoolLibri\",\"https:\/\/x.com\/coollibri\",\"https:\/\/www.instagram.com\/coollibri\/\",\"https:\/\/www.linkedin.com\/company\/coollibri\/\",\"https:\/\/www.youtube.com\/channel\/UCg6CQOMq_0Q1Rc6DsIak0-w\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.coollibri.com\/blog\/#\/schema\/person\/5105fe42ec9d3fe2661138a0d65013c7\",\"name\":\"CoolLibri Impression de livre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.coollibri.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7112ca292ee176a5d7b66db3caf74cd9?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7112ca292ee176a5d7b66db3caf74cd9?s=96&r=g\",\"caption\":\"CoolLibri Impression de livre\"}}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La litt\u00e9rature fantastique pour la jeunesse est un genre plein de ressources","description":"La litt\u00e9rature fantastique est un bon moyen pour la jeunesse de d\u00e9couvrir ce que la lecture peut apporter pour son d\u00e9veloppement personnel.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.coollibri.com\/blog\/livres-litterature-fantastique-jeunesse\/","og_locale":"fr_FR","og_type":"article","og_title":"La litt\u00e9rature fantastique pour la jeunesse est un genre plein de ressources","og_description":"La litt\u00e9rature fantastique est un bon moyen pour la jeunesse de d\u00e9couvrir ce que la lecture peut apporter pour son d\u00e9veloppement personnel.","og_url":"https:\/\/www.coollibri.com\/blog\/livres-litterature-fantastique-jeunesse\/","og_site_name":"\u00c9crire un livre et auto\u00e9dition, le blog.","article_publisher":"https:\/\/www.facebook.com\/CoolLibri","article_published_time":"2020-06-17T06:30:13+00:00","article_modified_time":"2020-12-28T06:12:08+00:00","og_image":[{"width":1500,"height":500,"url":"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/12-livres-de-litt\u00e9rature-fantastique.jpg","type":"image\/jpeg"}],"author":"CoolLibri Impression de livre","twitter_card":"summary_large_image","twitter_creator":"@coollibri","twitter_site":"@coollibri","twitter_misc":{"\u00c9crit par":"CoolLibri Impression de livre","Dur\u00e9e de lecture estim\u00e9e":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.coollibri.com\/blog\/livres-litterature-fantastique-jeunesse\/#article","isPartOf":{"@id":"https:\/\/www.coollibri.com\/blog\/livres-litterature-fantastique-jeunesse\/"},"author":{"name":"CoolLibri Impression de livre","@id":"https:\/\/www.coollibri.com\/blog\/#\/schema\/person\/5105fe42ec9d3fe2661138a0d65013c7"},"headline":"12 livres de litt\u00e9rature fantastique pour la jeunesse \u00e0 ne pas manquer","datePublished":"2020-06-17T06:30:13+00:00","dateModified":"2020-12-28T06:12:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.coollibri.com\/blog\/livres-litterature-fantastique-jeunesse\/"},"wordCount":3047,"commentCount":1,"publisher":{"@id":"https:\/\/www.coollibri.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.coollibri.com\/blog\/livres-litterature-fantastique-jeunesse\/#primaryimage"},"thumbnailUrl":"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/12-livres-de-litt\u00e9rature-fantastique.jpg","keywords":["livres d'aventures fantastiquess","livres de dragons","livres de magiciens","livres fantastiques pour la jeunesse"],"articleSection":["\u00c9crire un livre"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.coollibri.com\/blog\/livres-litterature-fantastique-jeunesse\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.coollibri.com\/blog\/livres-litterature-fantastique-jeunesse\/","url":"https:\/\/www.coollibri.com\/blog\/livres-litterature-fantastique-jeunesse\/","name":"La litt\u00e9rature fantastique pour la jeunesse est un genre plein de ressources","isPartOf":{"@id":"https:\/\/www.coollibri.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.coollibri.com\/blog\/livres-litterature-fantastique-jeunesse\/#primaryimage"},"image":{"@id":"https:\/\/www.coollibri.com\/blog\/livres-litterature-fantastique-jeunesse\/#primaryimage"},"thumbnailUrl":"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/12-livres-de-litt\u00e9rature-fantastique.jpg","datePublished":"2020-06-17T06:30:13+00:00","dateModified":"2020-12-28T06:12:08+00:00","description":"La litt\u00e9rature fantastique est un bon moyen pour la jeunesse de d\u00e9couvrir ce que la lecture peut apporter pour son d\u00e9veloppement personnel.","breadcrumb":{"@id":"https:\/\/www.coollibri.com\/blog\/livres-litterature-fantastique-jeunesse\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.coollibri.com\/blog\/livres-litterature-fantastique-jeunesse\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.coollibri.com\/blog\/livres-litterature-fantastique-jeunesse\/#primaryimage","url":"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/12-livres-de-litt\u00e9rature-fantastique.jpg","contentUrl":"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/12-livres-de-litt\u00e9rature-fantastique.jpg","width":1500,"height":500,"caption":"12 livres de litt\u00e9rature fantastique"},{"@type":"BreadcrumbList","@id":"https:\/\/www.coollibri.com\/blog\/livres-litterature-fantastique-jeunesse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.coollibri.com\/blog\/"},{"@type":"ListItem","position":2,"name":"12 livres de litt\u00e9rature fantastique pour la jeunesse \u00e0 ne pas manquer"}]},{"@type":"WebSite","@id":"https:\/\/www.coollibri.com\/blog\/#website","url":"https:\/\/www.coollibri.com\/blog\/","name":"\u00c9crire un livre et auto\u00e9dition, le blog.","description":"Faites une bonne impression","publisher":{"@id":"https:\/\/www.coollibri.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.coollibri.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.coollibri.com\/blog\/#organization","name":"CoolLibri - Impression de livre - Auto\u00e9dition","url":"https:\/\/www.coollibri.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.coollibri.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/2018\/03\/logo.png","contentUrl":"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/2018\/03\/logo.png","width":231,"height":72,"caption":"CoolLibri - Impression de livre - Auto\u00e9dition"},"image":{"@id":"https:\/\/www.coollibri.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CoolLibri","https:\/\/x.com\/coollibri","https:\/\/www.instagram.com\/coollibri\/","https:\/\/www.linkedin.com\/company\/coollibri\/","https:\/\/www.youtube.com\/channel\/UCg6CQOMq_0Q1Rc6DsIak0-w"]},{"@type":"Person","@id":"https:\/\/www.coollibri.com\/blog\/#\/schema\/person\/5105fe42ec9d3fe2661138a0d65013c7","name":"CoolLibri Impression de livre","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.coollibri.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7112ca292ee176a5d7b66db3caf74cd9?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7112ca292ee176a5d7b66db3caf74cd9?s=96&r=g","caption":"CoolLibri Impression de livre"}}]}},"_links":{"self":[{"href":"https:\/\/www.coollibri.com\/blog\/wp-json\/wp\/v2\/posts\/5255"}],"collection":[{"href":"https:\/\/www.coollibri.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.coollibri.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.coollibri.com\/blog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.coollibri.com\/blog\/wp-json\/wp\/v2\/comments?post=5255"}],"version-history":[{"count":49,"href":"https:\/\/www.coollibri.com\/blog\/wp-json\/wp\/v2\/posts\/5255\/revisions"}],"predecessor-version":[{"id":6730,"href":"https:\/\/www.coollibri.com\/blog\/wp-json\/wp\/v2\/posts\/5255\/revisions\/6730"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.coollibri.com\/blog\/wp-json\/wp\/v2\/media\/5300"}],"wp:attachment":[{"href":"https:\/\/www.coollibri.com\/blog\/wp-json\/wp\/v2\/media?parent=5255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.coollibri.com\/blog\/wp-json\/wp\/v2\/categories?post=5255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.coollibri.com\/blog\/wp-json\/wp\/v2\/tags?post=5255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}