{"id":1025,"count":1,"description":"","link":"https:\/\/www.coollibri.com\/blog\/tag\/figures-de-style-dopposition\/","name":"figures de style d'opposition","slug":"figures-de-style-dopposition","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>figures de style d&#039;opposition Archives - \u00c9crire un livre et auto\u00e9dition, le blog.<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.coollibri.com\/blog\/tag\/figures-de-style-dopposition\/\" \/>\r\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"figures de style d&#039;opposition Archives - \u00c9crire un livre et auto\u00e9dition, le blog.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.coollibri.com\/blog\/tag\/figures-de-style-dopposition\/\" \/>\r\n<meta property=\"og:site_name\" content=\"\u00c9crire un livre et auto\u00e9dition, le blog.\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:site\" content=\"@coollibri\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.coollibri.com\/blog\/tag\/figures-de-style-dopposition\/\",\"url\":\"https:\/\/www.coollibri.com\/blog\/tag\/figures-de-style-dopposition\/\",\"name\":\"figures de style d'opposition Archives - \u00c9crire un livre et auto\u00e9dition, le blog.\",\"isPartOf\":{\"@id\":\"https:\/\/www.coollibri.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.coollibri.com\/blog\/tag\/figures-de-style-dopposition\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.coollibri.com\/blog\/tag\/figures-de-style-dopposition\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.coollibri.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"figures de style d'opposition\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.coollibri.com\/blog\/#website\",\"url\":\"https:\/\/www.coollibri.com\/blog\/\",\"name\":\"\u00c9crire un livre et auto\u00e9dition, le blog.\",\"description\":\"Faites une bonne impression\",\"publisher\":{\"@id\":\"https:\/\/www.coollibri.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.coollibri.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.coollibri.com\/blog\/#organization\",\"name\":\"CoolLibri - Impression de livre - Auto\u00e9dition\",\"url\":\"https:\/\/www.coollibri.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.coollibri.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/2018\/03\/logo.png\",\"contentUrl\":\"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/2018\/03\/logo.png\",\"width\":231,\"height\":72,\"caption\":\"CoolLibri - Impression de livre - Auto\u00e9dition\"},\"image\":{\"@id\":\"https:\/\/www.coollibri.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/CoolLibri\",\"https:\/\/x.com\/coollibri\",\"https:\/\/www.instagram.com\/coollibri\/\",\"https:\/\/www.linkedin.com\/company\/coollibri\/\",\"https:\/\/www.youtube.com\/channel\/UCg6CQOMq_0Q1Rc6DsIak0-w\"]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"figures de style d'opposition Archives - \u00c9crire un livre et auto\u00e9dition, le blog.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.coollibri.com\/blog\/tag\/figures-de-style-dopposition\/","og_locale":"fr_FR","og_type":"article","og_title":"figures de style d'opposition Archives - \u00c9crire un livre et auto\u00e9dition, le blog.","og_url":"https:\/\/www.coollibri.com\/blog\/tag\/figures-de-style-dopposition\/","og_site_name":"\u00c9crire un livre et auto\u00e9dition, le blog.","twitter_card":"summary_large_image","twitter_site":"@coollibri","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.coollibri.com\/blog\/tag\/figures-de-style-dopposition\/","url":"https:\/\/www.coollibri.com\/blog\/tag\/figures-de-style-dopposition\/","name":"figures de style d'opposition Archives - \u00c9crire un livre et auto\u00e9dition, le blog.","isPartOf":{"@id":"https:\/\/www.coollibri.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.coollibri.com\/blog\/tag\/figures-de-style-dopposition\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.coollibri.com\/blog\/tag\/figures-de-style-dopposition\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.coollibri.com\/blog\/"},{"@type":"ListItem","position":2,"name":"figures de style d'opposition"}]},{"@type":"WebSite","@id":"https:\/\/www.coollibri.com\/blog\/#website","url":"https:\/\/www.coollibri.com\/blog\/","name":"\u00c9crire un livre et auto\u00e9dition, le blog.","description":"Faites une bonne impression","publisher":{"@id":"https:\/\/www.coollibri.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.coollibri.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.coollibri.com\/blog\/#organization","name":"CoolLibri - Impression de livre - Auto\u00e9dition","url":"https:\/\/www.coollibri.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.coollibri.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/2018\/03\/logo.png","contentUrl":"https:\/\/www.coollibri.com\/blog\/wp-content\/uploads\/2018\/03\/logo.png","width":231,"height":72,"caption":"CoolLibri - Impression de livre - Auto\u00e9dition"},"image":{"@id":"https:\/\/www.coollibri.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CoolLibri","https:\/\/x.com\/coollibri","https:\/\/www.instagram.com\/coollibri\/","https:\/\/www.linkedin.com\/company\/coollibri\/","https:\/\/www.youtube.com\/channel\/UCg6CQOMq_0Q1Rc6DsIak0-w"]}]}},"_links":{"self":[{"href":"https:\/\/www.coollibri.com\/blog\/wp-json\/wp\/v2\/tags\/1025"}],"collection":[{"href":"https:\/\/www.coollibri.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.coollibri.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.coollibri.com\/blog\/wp-json\/wp\/v2\/posts?tags=1025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}